{"id":3071,"date":"2017-09-12T14:48:29","date_gmt":"2017-09-12T12:48:29","guid":{"rendered":"http:\/\/indic.cat\/web\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/"},"modified":"2017-10-24T10:29:45","modified_gmt":"2017-10-24T08:29:45","slug":"pla-local-dinfancia-adolescencia-sant-andreu-barca-2017","status":"publish","type":"projecte","link":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/","title":{"rendered":"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017)"},"content":{"rendered":"<p><span lang=\"es\">Para abordar el an\u00e1lisis de la situaci\u00f3n actual de la infancia y la adolescencia de San Andreu de la Barca se utilizaron tres estrategias: <\/span><\/p>\n<ul>\n<li><span lang=\"es\">la recopilaci\u00f3n de datos que permitiera una aproximaci\u00f3n cuantitativa a la realidad de los ni\u00f1os y adolescentes del municipio<\/span><\/li>\n<li><span lang=\"es\">la recopilaci\u00f3n de servicios y recursos que desde las diferentes \u00e1reas o departamentos municipales desarrollan para ni\u00f1os y adolescentes<\/span><\/li>\n<li><span lang=\"es\">la recopilaci\u00f3n de visiones en torno a las tem\u00e1ticas abordadas<\/span><\/li>\n<\/ul>\n<p><span lang=\"es\">Se realizaron sesiones de trabajo participativas en los diferentes espacios del proyecto y agentes implicados con el fin de realizar una aprox<\/span><span lang=\"es\">imaci\u00f3n cualitativa desde el punto de vista t\u00e9cnico entorno a las principales necesidades de los ni\u00f1os y adolescentes del municipio<\/span><\/p>\n<p><span lang=\"es\">Se cre\u00f3 un Grupo Motor con participaci\u00f3n de los servicios de Educaci\u00f3n, Salud P\u00fablica, Juventud, Participaci\u00f3n y Servicios Sociales y se hicieron sesiones con t\u00e9cnicos y t\u00e9cnicas municipales, sesi\u00f3n con profesionales de servicios y recursos externos sesi\u00f3n con agentes sociales del territorio\u00a0 y talleres participativos con alumnos de centros de ense\u00f1anza.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para abordar el an\u00e1lisis de la situaci\u00f3n actual de la infancia y la adolescencia de San Andreu de la Barca se utilizaron tres estrategias: la recopilaci\u00f3n de datos que permitiera una aproximaci\u00f3n cuantitativa a la realidad de los ni\u00f1os y adolescentes del municipio la recopilaci\u00f3n de servicios y recursos que desde las diferentes \u00e1reas o [&hellip;]<\/p>\n","protected":false},"featured_media":2600,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-servei":[],"class_list":["post-3071","projecte","type-projecte","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS\" \/>\n<meta property=\"og:description\" content=\"Para abordar el an\u00e1lisis de la situaci\u00f3n actual de la infancia y la adolescencia de San Andreu de la Barca se utilizaron tres estrategias: la recopilaci\u00f3n de datos que permitiera una aproximaci\u00f3n cuantitativa a la realidad de los ni\u00f1os y adolescentes del municipio la recopilaci\u00f3n de servicios y recursos que desde las diferentes \u00e1reas o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"My CMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-24T08:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indic.cat\/wp-content\/uploads\/2017\/09\/2017-07-13-11.05.09-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IndicSL\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/\",\"url\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/\",\"name\":\"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-07-13-11.05.09.jpg\",\"datePublished\":\"2017-09-12T12:48:29+00:00\",\"dateModified\":\"2017-10-24T08:29:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-07-13-11.05.09.jpg\",\"contentUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/2017-07-13-11.05.09.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/indic.cat\\\/es\\\/iniciativas-y-dinamicas-comunitarias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/indic.cat\\\/projecte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\",\"url\":\"https:\\\/\\\/indic.cat\\\/\",\"name\":\"My CMS\",\"description\":\"Iniciatives i din\u00e0miques comunit\u00e0ries\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indic.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/","og_locale":"es_ES","og_type":"article","og_title":"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS","og_description":"Para abordar el an\u00e1lisis de la situaci\u00f3n actual de la infancia y la adolescencia de San Andreu de la Barca se utilizaron tres estrategias: la recopilaci\u00f3n de datos que permitiera una aproximaci\u00f3n cuantitativa a la realidad de los ni\u00f1os y adolescentes del municipio la recopilaci\u00f3n de servicios y recursos que desde las diferentes \u00e1reas o [&hellip;]","og_url":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/","og_site_name":"My CMS","article_publisher":"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/","article_modified_time":"2017-10-24T08:29:45+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/indic.cat\/wp-content\/uploads\/2017\/09\/2017-07-13-11.05.09-1024x768.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@IndicSL","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/","url":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/","name":"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017) - My CMS","isPartOf":{"@id":"https:\/\/indic.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/#primaryimage"},"image":{"@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2017\/09\/2017-07-13-11.05.09.jpg","datePublished":"2017-09-12T12:48:29+00:00","dateModified":"2017-10-24T08:29:45+00:00","breadcrumb":{"@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/#primaryimage","url":"https:\/\/indic.cat\/wp-content\/uploads\/2017\/09\/2017-07-13-11.05.09.jpg","contentUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2017\/09\/2017-07-13-11.05.09.jpg","width":3264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/indic.cat\/es\/projecte\/pla-local-dinfancia-adolescencia-sant-andreu-barca-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/indic.cat\/es\/iniciativas-y-dinamicas-comunitarias\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/indic.cat\/projecte\/"},{"@type":"ListItem","position":3,"name":"Plan local de infancia y adolescencia de Sant Andreu de la Barca (2017)"}]},{"@type":"WebSite","@id":"https:\/\/indic.cat\/#website","url":"https:\/\/indic.cat\/","name":"My CMS","description":"Iniciatives i din\u00e0miques comunit\u00e0ries","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indic.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/types\/projecte"}],"version-history":[{"count":2,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3071\/revisions"}],"predecessor-version":[{"id":3073,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3071\/revisions\/3073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media\/2600"}],"wp:attachment":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media?parent=3071"}],"wp:term":[{"taxonomy":"categoria-servei","embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/categoria-servei?post=3071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}