{"id":3880,"date":"2023-09-08T08:59:13","date_gmt":"2023-09-08T06:59:13","guid":{"rendered":"https:\/\/indic.cat\/?post_type=projecte&#038;p=3880"},"modified":"2024-07-26T11:11:28","modified_gmt":"2024-07-26T09:11:28","slug":"12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023","status":"publish","type":"projecte","link":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/","title":{"rendered":"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023)"},"content":{"rendered":"<p>INDIC ha dinamizado la 12a edici\u00f3n de los Espacios de intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI), curso 2022-2023, impulsado desde el Servicio de Convivencia, Diversidad y Ciclo de Vida de la Diputaci\u00f3n de Barcelona. \u00c9ste es un espacio de intercambio de conocimientos entre los municipios y consejos comarcales que est\u00e1n trabajando con un PLACI con la voluntad de ser un espacio de reflexi\u00f3n, para compartir experiencias y abordar temas concretos y construir propuestas vinculadas a la inclusi\u00f3n y la acci\u00f3n comunitaria .<\/p>\n<p>Las tareas principales desarrolladas por INDIC han sido:<\/p>\n<ul>\n<li>Dise\u00f1o del curso y estructuraci\u00f3n de los encuentros de los espacios de intercambio as\u00ed como sus contenidos a tratar.<\/li>\n<li>Organizaci\u00f3n y dinamizaci\u00f3n de las sesiones para favorecer un espacio de conocimiento y de intercambio de experiencias entre los distintos entes participantes y la generaci\u00f3n de ideas en una parte de trabajo conjunto.<\/li>\n<li>Redacci\u00f3n del informe de resultados del trabajo realizado y de los aprendizajes adquiridos en cada uno de los encuentros.<\/li>\n<li>Redacci\u00f3n del informe final con los resultados del trabajo realizado y los aprendizajes de todo el curso y el an\u00e1lisis de las valoraciones de los participantes y posibles oportunidades de mejora para pr\u00f3ximas ediciones.<\/li>\n<li>Elaboraci\u00f3n de infograf\u00edas resumen de las sesiones y fichas de experiencias para compartir en el espacio virtual del curso.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>INDIC ha dinamizado la 12a edici\u00f3n de los Espacios de intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI), curso 2022-2023, impulsado desde el Servicio de Convivencia, Diversidad y Ciclo de Vida de la Diputaci\u00f3n de Barcelona. \u00c9ste es un espacio de intercambio de conocimientos entre los municipios y consejos comarcales que est\u00e1n trabajando [&hellip;]<\/p>\n","protected":false},"featured_media":3881,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-servei":[19],"class_list":["post-3880","projecte","type-projecte","status-publish","has-post-thumbnail","hentry","categoria-servei-consultoria-participacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS\" \/>\n<meta property=\"og:description\" content=\"INDIC ha dinamizado la 12a edici\u00f3n de los Espacios de intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI), curso 2022-2023, impulsado desde el Servicio de Convivencia, Diversidad y Ciclo de Vida de la Diputaci\u00f3n de Barcelona. \u00c9ste es un espacio de intercambio de conocimientos entre los municipios y consejos comarcales que est\u00e1n trabajando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"My CMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-26T09:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/ESPAIS-placi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IndicSL\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/\",\"url\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/\",\"name\":\"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/ESPAIS-placi.jpg\",\"datePublished\":\"2023-09-08T06:59:13+00:00\",\"dateModified\":\"2024-07-26T09:11:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/ESPAIS-placi.jpg\",\"contentUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/ESPAIS-placi.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/indic.cat\\\/es\\\/iniciativas-y-dinamicas-comunitarias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/indic.cat\\\/projecte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\",\"url\":\"https:\\\/\\\/indic.cat\\\/\",\"name\":\"My CMS\",\"description\":\"Iniciatives i din\u00e0miques comunit\u00e0ries\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indic.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/","og_locale":"es_ES","og_type":"article","og_title":"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS","og_description":"INDIC ha dinamizado la 12a edici\u00f3n de los Espacios de intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI), curso 2022-2023, impulsado desde el Servicio de Convivencia, Diversidad y Ciclo de Vida de la Diputaci\u00f3n de Barcelona. \u00c9ste es un espacio de intercambio de conocimientos entre los municipios y consejos comarcales que est\u00e1n trabajando [&hellip;]","og_url":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/","og_site_name":"My CMS","article_publisher":"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/","article_modified_time":"2024-07-26T09:11:28+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/ESPAIS-placi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@IndicSL","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/","url":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/","name":"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023) - My CMS","isPartOf":{"@id":"https:\/\/indic.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/#primaryimage"},"image":{"@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/ESPAIS-placi.jpg","datePublished":"2023-09-08T06:59:13+00:00","dateModified":"2024-07-26T09:11:28+00:00","breadcrumb":{"@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/#primaryimage","url":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/ESPAIS-placi.jpg","contentUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/ESPAIS-placi.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/indic.cat\/es\/projecte\/12a-edicio-dels-espais-dintercanvi-dels-plans-locals-daccio-comunitaria-inclusiva-placi-diputacio-de-barcelona-2022-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/indic.cat\/es\/iniciativas-y-dinamicas-comunitarias\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/indic.cat\/projecte\/"},{"@type":"ListItem","position":3,"name":"12a edici\u00f3n de los Espacios de Intercambio de los Planes Locales de Acci\u00f3n Comunitaria Inclusiva (PLACI) Diputaci\u00f3n de Barcelona (2022-2023)"}]},{"@type":"WebSite","@id":"https:\/\/indic.cat\/#website","url":"https:\/\/indic.cat\/","name":"My CMS","description":"Iniciatives i din\u00e0miques comunit\u00e0ries","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indic.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/types\/projecte"}],"version-history":[{"count":5,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3880\/revisions"}],"predecessor-version":[{"id":6099,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/3880\/revisions\/6099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media\/3881"}],"wp:attachment":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media?parent=3880"}],"wp:term":[{"taxonomy":"categoria-servei","embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/categoria-servei?post=3880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}