{"id":4291,"date":"2023-09-21T10:24:18","date_gmt":"2023-09-21T08:24:18","guid":{"rendered":"https:\/\/indic.cat\/?post_type=projecte&#038;p=4291"},"modified":"2024-07-29T09:39:23","modified_gmt":"2024-07-29T07:39:23","slug":"encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023","status":"publish","type":"projecte","link":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/","title":{"rendered":"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023)"},"content":{"rendered":"<p>INDIC ha dinamizado varios encuentros en l\u00ednea organizados por el \u00c1rea de Educaci\u00f3n, Deportes y Juventud de Diputaci\u00f3n de Barcelona con miembros de la Red de Guarder\u00edas con el objetivo de generar un espacio donde poder compartir sus desazones, reflexiones o aportaciones sobre aquellos temas de su inter\u00e9s.<\/p>\n<p>A las sesiones participaron perfiles diversos desde responsables t\u00e9cnicos municipales hasta equipos directivos de guarder\u00edas municipales.<\/p>\n<p>Las tareas que se desarrollaron fueron:<\/p>\n<p>Coordinaci\u00f3n, dise\u00f1o y apoyo metodol\u00f3gico del encuentro en l\u00ednea.<br \/>\nDinamizaci\u00f3n de la jornada.<br \/>\nElaboraci\u00f3n de los informes con los resultados de las reflexiones y aportaciones hechas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INDIC ha dinamizado varios encuentros en l\u00ednea organizados por el \u00c1rea de Educaci\u00f3n, Deportes y Juventud de Diputaci\u00f3n de Barcelona con miembros de la Red de Guarder\u00edas con el objetivo de generar un espacio donde poder compartir sus desazones, reflexiones o aportaciones sobre aquellos temas de su inter\u00e9s. A las sesiones participaron perfiles diversos desde [&hellip;]<\/p>\n","protected":false},"featured_media":4022,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categoria-servei":[],"class_list":["post-4291","projecte","type-projecte","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS\" \/>\n<meta property=\"og:description\" content=\"INDIC ha dinamizado varios encuentros en l\u00ednea organizados por el \u00c1rea de Educaci\u00f3n, Deportes y Juventud de Diputaci\u00f3n de Barcelona con miembros de la Red de Guarder\u00edas con el objetivo de generar un espacio donde poder compartir sus desazones, reflexiones o aportaciones sobre aquellos temas de su inter\u00e9s. A las sesiones participaron perfiles diversos desde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"My CMS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T07:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/1.14.-Jornada-Compartim-petits-XEB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IndicSL\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/\",\"url\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/\",\"name\":\"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1.14.-Jornada-Compartim-petits-XEB.png\",\"datePublished\":\"2023-09-21T08:24:18+00:00\",\"dateModified\":\"2024-07-29T07:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1.14.-Jornada-Compartim-petits-XEB.png\",\"contentUrl\":\"https:\\\/\\\/indic.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1.14.-Jornada-Compartim-petits-XEB.png\",\"width\":816,\"height\":541,\"caption\":\"1.14. Jornada Compartim petits - XEB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indic.cat\\\/es\\\/projecte\\\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/indic.cat\\\/es\\\/iniciativas-y-dinamicas-comunitarias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/indic.cat\\\/projecte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indic.cat\\\/#website\",\"url\":\"https:\\\/\\\/indic.cat\\\/\",\"name\":\"My CMS\",\"description\":\"Iniciatives i din\u00e0miques comunit\u00e0ries\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indic.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS","og_description":"INDIC ha dinamizado varios encuentros en l\u00ednea organizados por el \u00c1rea de Educaci\u00f3n, Deportes y Juventud de Diputaci\u00f3n de Barcelona con miembros de la Red de Guarder\u00edas con el objetivo de generar un espacio donde poder compartir sus desazones, reflexiones o aportaciones sobre aquellos temas de su inter\u00e9s. A las sesiones participaron perfiles diversos desde [&hellip;]","og_url":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/","og_site_name":"My CMS","article_publisher":"https:\/\/www.facebook.com\/Indic-Iniciatives-i-Din%c3%a0miques-Comunit%c3%a0ries-362170033806658\/","article_modified_time":"2024-07-29T07:39:23+00:00","og_image":[{"width":816,"height":541,"url":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/1.14.-Jornada-Compartim-petits-XEB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@IndicSL","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/","url":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/","name":"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023) - My CMS","isPartOf":{"@id":"https:\/\/indic.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/#primaryimage"},"image":{"@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/1.14.-Jornada-Compartim-petits-XEB.png","datePublished":"2023-09-21T08:24:18+00:00","dateModified":"2024-07-29T07:39:23+00:00","breadcrumb":{"@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/#primaryimage","url":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/1.14.-Jornada-Compartim-petits-XEB.png","contentUrl":"https:\/\/indic.cat\/wp-content\/uploads\/2023\/09\/1.14.-Jornada-Compartim-petits-XEB.png","width":816,"height":541,"caption":"1.14. Jornada Compartim petits - XEB"},{"@type":"BreadcrumbList","@id":"https:\/\/indic.cat\/es\/projecte\/encuentro-de-la-red-de-guarderias-municipales-compartimos-pequenos-municipios-diputacion-de-barcelona-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/indic.cat\/es\/iniciativas-y-dinamicas-comunitarias\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/indic.cat\/projecte\/"},{"@type":"ListItem","position":3,"name":"Encuentro de la Red de Guarder\u00edas Municipales \u2013 Compartimos peque\u00f1os municipios. Diputaci\u00f3n de Barcelona (2023)"}]},{"@type":"WebSite","@id":"https:\/\/indic.cat\/#website","url":"https:\/\/indic.cat\/","name":"My CMS","description":"Iniciatives i din\u00e0miques comunit\u00e0ries","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indic.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/4291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte"}],"about":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/types\/projecte"}],"version-history":[{"count":3,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/4291\/revisions"}],"predecessor-version":[{"id":6170,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/projecte\/4291\/revisions\/6170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media\/4022"}],"wp:attachment":[{"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/media?parent=4291"}],"wp:term":[{"taxonomy":"categoria-servei","embeddable":true,"href":"https:\/\/indic.cat\/es\/wp-json\/wp\/v2\/categoria-servei?post=4291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}